{"id":3776,"date":"2021-04-12T19:39:26","date_gmt":"2021-04-12T17:39:26","guid":{"rendered":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2.jpg"},"modified":"2026-03-31T12:17:11","modified_gmt":"2026-03-31T10:17:11","slug":"ses-arenes-twins-sala-2-2","status":"inherit","type":"attachment","link":"https:\/\/www.sesarenes.com\/it\/ses-arenes-twins-sala-2-2\/","title":{"rendered":"Ses-Arenes-Twins-Sala-2"},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-3776","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"WebMaster\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.sesarenes.com\/it\/ses-arenes-twins-sala-2-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/ses-arenes-twins-sala-2-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/ses-arenes-twins-sala-2-2\\\/#listItem\",\"name\":\"Ses-Arenes-Twins-Sala-2\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/ses-arenes-twins-sala-2-2\\\/#listItem\",\"position\":2,\"name\":\"Ses-Arenes-Twins-Sala-2\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/ses-arenes-twins-sala-2-2\\\/#itempage\",\"url\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/ses-arenes-twins-sala-2-2\\\/\",\"name\":\"Ses-Arenes-Twins-Sala-2 | Ses Arenes. Agroturismo de Colonia de Sant Jordi. Mallorca\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/ses-arenes-twins-sala-2-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/author\\\/sesarenesferranforteza-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/author\\\/sesarenesferranforteza-com\\\/#author\"},\"datePublished\":\"2021-04-12T19:39:26+02:00\",\"dateModified\":\"2026-03-31T12:17:11+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/#organization\",\"name\":\"Ses Arenes Agroturismo\",\"description\":\"Ses Arenes: El sue\\u00f1o de unas vacaciones en Mallorca\",\"url\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/\",\"telephone\":\"+34971655400\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.sesarenes.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/ses_Arenes_Logo_fons.png\",\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/ses-arenes-twins-sala-2-2\\\/#organizationLogo\",\"width\":651,\"height\":651,\"caption\":\"Ses Arenes logo cuadrado\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/ses-arenes-twins-sala-2-2\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/author\\\/sesarenesferranforteza-com\\\/#author\",\"url\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/author\\\/sesarenesferranforteza-com\\\/\",\"name\":\"WebMaster\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/ses-arenes-twins-sala-2-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/166e7f3470674dc844734be1058dde832dc081648967fcd2b2893d9d4eb938d0?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"WebMaster\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/\",\"name\":\"Ses Arenes. Agroturismo de Colonia de Sant Jordi. Mallorca\",\"description\":\"Ses Arenes: El sue\\u00f1o de unas vacaciones en Mallorca\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sesarenes.com\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ses-Arenes-Twins-Sala-2 | Ses Arenes. Agroturismo de Colonia de Sant Jordi. Mallorca","description":"","canonical_url":"https:\/\/www.sesarenes.com\/it\/ses-arenes-twins-sala-2-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.sesarenes.com\/it\/ses-arenes-twins-sala-2-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.sesarenes.com\/it\/#listItem","position":1,"name":"Inicio","item":"https:\/\/www.sesarenes.com\/it\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.sesarenes.com\/it\/ses-arenes-twins-sala-2-2\/#listItem","name":"Ses-Arenes-Twins-Sala-2"}},{"@type":"ListItem","@id":"https:\/\/www.sesarenes.com\/it\/ses-arenes-twins-sala-2-2\/#listItem","position":2,"name":"Ses-Arenes-Twins-Sala-2","previousItem":{"@type":"ListItem","@id":"https:\/\/www.sesarenes.com\/it\/#listItem","name":"Inicio"}}]},{"@type":"ItemPage","@id":"https:\/\/www.sesarenes.com\/it\/ses-arenes-twins-sala-2-2\/#itempage","url":"https:\/\/www.sesarenes.com\/it\/ses-arenes-twins-sala-2-2\/","name":"Ses-Arenes-Twins-Sala-2 | Ses Arenes. Agroturismo de Colonia de Sant Jordi. Mallorca","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.sesarenes.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/www.sesarenes.com\/it\/ses-arenes-twins-sala-2-2\/#breadcrumblist"},"author":{"@id":"https:\/\/www.sesarenes.com\/it\/author\/sesarenesferranforteza-com\/#author"},"creator":{"@id":"https:\/\/www.sesarenes.com\/it\/author\/sesarenesferranforteza-com\/#author"},"datePublished":"2021-04-12T19:39:26+02:00","dateModified":"2026-03-31T12:17:11+02:00"},{"@type":"Organization","@id":"https:\/\/www.sesarenes.com\/it\/#organization","name":"Ses Arenes Agroturismo","description":"Ses Arenes: El sue\u00f1o de unas vacaciones en Mallorca","url":"https:\/\/www.sesarenes.com\/it\/","telephone":"+34971655400","logo":{"@type":"ImageObject","url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2016\/01\/ses_Arenes_Logo_fons.png","@id":"https:\/\/www.sesarenes.com\/it\/ses-arenes-twins-sala-2-2\/#organizationLogo","width":651,"height":651,"caption":"Ses Arenes logo cuadrado"},"image":{"@id":"https:\/\/www.sesarenes.com\/it\/ses-arenes-twins-sala-2-2\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.sesarenes.com\/it\/author\/sesarenesferranforteza-com\/#author","url":"https:\/\/www.sesarenes.com\/it\/author\/sesarenesferranforteza-com\/","name":"WebMaster","image":{"@type":"ImageObject","@id":"https:\/\/www.sesarenes.com\/it\/ses-arenes-twins-sala-2-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/166e7f3470674dc844734be1058dde832dc081648967fcd2b2893d9d4eb938d0?s=96&d=mm&r=g","width":96,"height":96,"caption":"WebMaster"}},{"@type":"WebSite","@id":"https:\/\/www.sesarenes.com\/it\/#website","url":"https:\/\/www.sesarenes.com\/it\/","name":"Ses Arenes. Agroturismo de Colonia de Sant Jordi. Mallorca","description":"Ses Arenes: El sue\u00f1o de unas vacaciones en Mallorca","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.sesarenes.com\/it\/#organization"}}]}},"aioseo_meta_data":{"post_id":"3776","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-04-12 17:43:10","updated":"2026-04-13 10:08:35","seo_analyzer_scan_date":null},"description":{"rendered":"<p class=\"attachment\"><a data-rel=\"iLightbox[postimages]\" data-title=\"\" data-caption=\"\" href='https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-300x200.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271100%27%20height%3D%27733%27%20viewBox%3D%270%200%201100%20733%27%3E%3Crect%20width%3D%271100%27%20height%3D%27733%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-300x200.jpg\" data-srcset=\"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-200x133.jpg 200w, https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-300x200.jpg 300w, https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-400x267.jpg 400w, https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-600x400.jpg 600w, https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-768x512.jpg 768w, https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-800x533.jpg 800w, https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-1024x682.jpg 1024w, https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2.jpg 1100w\" data-sizes=\"auto\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1100,"height":733,"file":"2021\/04\/Ses-Arenes-Twins-Sala-2.jpg","sizes":{"medium":{"file":"Ses-Arenes-Twins-Sala-2-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-300x200.jpg"},"large":{"file":"Ses-Arenes-Twins-Sala-2-1024x682.jpg","width":1024,"height":682,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-1024x682.jpg"},"thumbnail":{"file":"Ses-Arenes-Twins-Sala-2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-150x150.jpg"},"medium_large":{"file":"Ses-Arenes-Twins-Sala-2-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-768x512.jpg"},"blog-large":{"file":"Ses-Arenes-Twins-Sala-2-669x272.jpg","width":669,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-669x272.jpg"},"blog-medium":{"file":"Ses-Arenes-Twins-Sala-2-320x202.jpg","width":320,"height":202,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-320x202.jpg"},"recent-posts":{"file":"Ses-Arenes-Twins-Sala-2-700x441.jpg","width":700,"height":441,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-700x441.jpg"},"recent-works-thumbnail":{"file":"Ses-Arenes-Twins-Sala-2-66x66.jpg","width":66,"height":66,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-66x66.jpg"},"fusion-200":{"file":"Ses-Arenes-Twins-Sala-2-200x133.jpg","width":200,"height":133,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-200x133.jpg"},"fusion-400":{"file":"Ses-Arenes-Twins-Sala-2-400x267.jpg","width":400,"height":267,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-400x267.jpg"},"fusion-600":{"file":"Ses-Arenes-Twins-Sala-2-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-600x400.jpg"},"fusion-800":{"file":"Ses-Arenes-Twins-Sala-2-800x533.jpg","width":800,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-800x533.jpg"},"portfolio-full":{"file":"Ses-Arenes-Twins-Sala-2-940x400.jpg","width":940,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-940x400.jpg"},"portfolio-one":{"file":"Ses-Arenes-Twins-Sala-2-540x272.jpg","width":540,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-540x272.jpg"},"portfolio-two":{"file":"Ses-Arenes-Twins-Sala-2-460x295.jpg","width":460,"height":295,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-460x295.jpg"},"portfolio-three":{"file":"Ses-Arenes-Twins-Sala-2-300x214.jpg","width":300,"height":214,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-300x214.jpg"},"portfolio-five":{"file":"Ses-Arenes-Twins-Sala-2-177x142.jpg","width":177,"height":142,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2-177x142.jpg"},"full":{"file":"Ses-Arenes-Twins-Sala-2.jpg","width":1100,"height":733,"mime_type":"image\/jpeg","source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.sesarenes.com\/wp-content\/uploads\/2021\/04\/Ses-Arenes-Twins-Sala-2.jpg","filename":"Ses-Arenes-Twins-Sala-2.jpg","filesize":108968,"_links":{"self":[{"href":"https:\/\/www.sesarenes.com\/it\/wp-json\/wp\/v2\/media\/3776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sesarenes.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.sesarenes.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.sesarenes.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sesarenes.com\/it\/wp-json\/wp\/v2\/comments?post=3776"}]}}